{"id":37621,"date":"2023-03-21T14:13:51","date_gmt":"2023-03-21T13:13:51","guid":{"rendered":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1.jpg"},"modified":"2023-03-21T14:13:51","modified_gmt":"2023-03-21T13:13:51","slug":"a1021_ceskyautosalon-1","status":"inherit","type":"attachment","link":"https:\/\/www.motorjournal.cz\/en\/?attachment_id=37621","title":{"rendered":"A1021_ceskyautosalon-1"},"author":46,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"kt_blocks_editor_width":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":""},"class_list":["post-37621","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a class=\"thumbnail\" href='https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1.jpg'><img decoding=\"async\" width=\"215\" height=\"300\" src=\"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-215x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-215x300.jpg 215w, https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-735x1024.jpg 735w, https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-768x1070.jpg 768w, https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-520x724.jpg 520w, https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-260x362.jpg 260w, https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1.jpg 850w\" sizes=\"(max-width: 215px) 100vw, 215px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":850,"height":1184,"file":"2023\/03\/A1021_ceskyautosalon-1.jpg","filesize":427167,"sizes":{"woocommerce_thumbnail":{"file":"A1021_ceskyautosalon-1-300x300.jpg","width":300,"height":300,"filesize":23517,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"A1021_ceskyautosalon-1-100x100.jpg","width":100,"height":100,"filesize":6843,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-100x100.jpg"},"woocommerce_single":{"file":"A1021_ceskyautosalon-1-456x615.jpg","width":456,"height":615,"filesize":61644,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-465x627.jpg"},"medium":{"file":"A1021_ceskyautosalon-1-215x300.jpg","width":215,"height":300,"filesize":19968,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-215x300.jpg"},"large":{"file":"A1021_ceskyautosalon-1-735x1024.jpg","width":735,"height":1024,"filesize":170884,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-735x1024.jpg"},"thumbnail":{"file":"A1021_ceskyautosalon-1-150x150.jpg","width":150,"height":150,"filesize":9792,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-150x150.jpg"},"medium_large":{"file":"A1021_ceskyautosalon-1-768x1070.jpg","width":768,"height":1070,"filesize":188375,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-768x1070.jpg"},"widget-thumb":{"file":"A1021_ceskyautosalon-1-80x50.jpg","width":80,"height":50,"filesize":5040,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-80x50.jpg"},"cmplz_banner_image":{"file":"A1021_ceskyautosalon-1-350x100.jpg","width":350,"height":100,"filesize":10515,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-350x100.jpg"},"sow-carousel-default":{"file":"A1021_ceskyautosalon-1-272x182.jpg","width":272,"height":182,"filesize":14442,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-272x182.jpg"},"kip-465x627":{"file":"A1021_ceskyautosalon-1-465x627.jpg","width":465,"height":627,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-465x627.jpg"},"kip-154x154":{"file":"A1021_ceskyautosalon-1-154x154.jpg","width":154,"height":154,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-154x154.jpg"},"kip-77x77":{"file":"A1021_ceskyautosalon-1-77x77.jpg","width":77,"height":77,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-77x77.jpg"},"kip-480x648":{"file":"A1021_ceskyautosalon-1-480x648.jpg","width":480,"height":648,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-480x648.jpg"},"kip-240x324":{"file":"A1021_ceskyautosalon-1-240x324.jpg","width":240,"height":324,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-240x324.jpg"},"kip-520x724":{"file":"A1021_ceskyautosalon-1-520x724.jpg","width":520,"height":724,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-520x724.jpg"},"kip-260x362":{"file":"A1021_ceskyautosalon-1-260x362.jpg","width":260,"height":362,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-260x362.jpg"},"kip-456x615":{"file":"A1021_ceskyautosalon-1-456x615.jpg","width":456,"height":615,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1-456x615.jpg"},"full":{"file":"A1021_ceskyautosalon-1.jpg","width":850,"height":1184,"mime_type":"image\/jpeg","source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"ScanMaker 9800XL","caption":"","created_timestamp":"1679405035","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":37620,"source_url":"https:\/\/www.motorjournal.cz\/wp-content\/uploads\/2023\/03\/A1021_ceskyautosalon-1.jpg","_links":{"self":[{"href":"https:\/\/www.motorjournal.cz\/en\/wp-json\/wp\/v2\/media\/37621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.motorjournal.cz\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.motorjournal.cz\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.motorjournal.cz\/en\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.motorjournal.cz\/en\/wp-json\/wp\/v2\/comments?post=37621"}],"wp:attached-to":[{"embeddable":true,"post_type":"product","id":37620,"href":"https:\/\/www.motorjournal.cz\/en\/wp-json\/wp\/v2\/product\/37620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}